{"id":5934,"date":"2022-10-26T14:34:53","date_gmt":"2022-10-26T13:34:53","guid":{"rendered":"https:\/\/iblow.eu\/regimes-gerais-de-protecao-de-denunciantes-de-infracoes-e-da-prevencao-da-corrupcao\/"},"modified":"2025-08-19T08:40:30","modified_gmt":"2025-08-19T07:40:30","slug":"regimes-gerais-de-protecao-de-denunciantes-de-infracoes-e-da-prevencao-da-corrupcao","status":"publish","type":"post","link":"https:\/\/iblow.eu\/pt\/regimes-gerais-de-protecao-de-denunciantes-de-infracoes-e-da-prevencao-da-corrupcao\/","title":{"rendered":"Regimes Gerais de Prote\u00e7\u00e3o de Denunciantes de Infra\u00e7\u00f5es e da Preven\u00e7\u00e3o da Corrup\u00e7\u00e3o"},"content":{"rendered":"<p><strong>Sabia que\u2026<\/strong><\/p>\n<p><strong>Os novos Regimes Gerais de Prote\u00e7\u00e3o de Denunciantes de Infra\u00e7\u00f5es e da Preven\u00e7\u00e3o da Corrup\u00e7\u00e3o encontram-se em vigor desde junho de 2022 e concretizam a Estrat\u00e9gia Nacional Anticorrup\u00e7\u00e3o 2020-2024?<\/strong><\/p>\n<p>Existem agora novos direitos para denunciantes, bem como novas obriga\u00e7\u00f5es para as empresas, de modo a melhor acompanhar de uma forma segura den\u00fancias de infra\u00e7\u00f5es e a combater a corrup\u00e7\u00e3o e criminalidade econ\u00f3mica na Uni\u00e3o Europeia.<\/p>\n<p>Entidades com 50 ou mais trabalhadores est\u00e3o obrigadas a criar um programa de cumprimento normativo, que inclui a implementa\u00e7\u00e3o de plano de preven\u00e7\u00e3o de riscos de corrup\u00e7\u00e3o, c\u00f3digo de conduta, programa de forma\u00e7\u00e3o interno e canais de den\u00fancia internos para dar seguimento a den\u00fancias de atos de corrup\u00e7\u00e3o ou qualquer outra irregularidade relacionada. Ficam ainda obrigadas n\u00e3o s\u00f3 a designar um respons\u00e1vel que garanta a aplica\u00e7\u00e3o do programa, como tamb\u00e9m a criar um sistema de avalia\u00e7\u00e3o para controlo e execu\u00e7\u00e3o do mesmo.<\/p>\n<p>No caso de viola\u00e7\u00e3o das obriga\u00e7\u00f5es previstas no Regime Geral da Preven\u00e7\u00e3o da Corrup\u00e7\u00e3o, as entidades obrigadas poder\u00e3o incorrer em contraordena\u00e7\u00e3o cujo montante varia entre 1.000\u20ac e 44.891,81\u20ac.<\/p>\n<p>Equipa DLA Piper\u00a0Portugal<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-1935 alignleft ls-is-cached lazyloaded\" src=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-300x241.jpg\" sizes=\"(max-width: 161px) 100vw, 161px\" srcset=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-300x241.jpg 300w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-1024x822.jpg 1024w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-768x616.jpg 768w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-1536x1233.jpg 1536w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-2048x1644.jpg 2048w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-600x482.jpg 600w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-500x401.jpg 500w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-400x321.jpg 400w\" alt=\"\" width=\"161\" height=\"129\" data-src=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-300x241.jpg\" data-srcset=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-300x241.jpg 300w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-1024x822.jpg 1024w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-768x616.jpg 768w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-1536x1233.jpg 1536w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-2048x1644.jpg 2048w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-600x482.jpg 600w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-500x401.jpg 500w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Reis_Daniel-400x321.jpg 400w\" data-sizes=\"(max-width: 161px) 100vw, 161px\" \/><img decoding=\"async\" class=\"alignnone wp-image-1943 alignleft ls-is-cached lazyloaded\" src=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho-300x300.jpeg\" sizes=\"(max-width: 129px) 100vw, 129px\" srcset=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho-300x300.jpeg 300w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho-150x150.jpeg 150w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho.jpeg 400w\" alt=\"\" width=\"129\" height=\"129\" data-src=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho-300x300.jpeg\" data-srcset=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho-300x300.jpeg 300w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho-150x150.jpeg 150w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Marta-Albuquerque-Coelho.jpeg 400w\" data-sizes=\"(max-width: 129px) 100vw, 129px\" \/><img decoding=\"async\" class=\"alignnone wp-image-1944 alignleft ls-is-cached lazyloaded\" src=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes-300x300.jpeg\" sizes=\"(max-width: 128px) 100vw, 128px\" srcset=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes-300x300.jpeg 300w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes-150x150.jpeg 150w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes.jpeg 400w\" alt=\"\" width=\"128\" height=\"128\" data-src=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes-300x300.jpeg\" data-srcset=\"https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes-300x300.jpeg 300w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes-150x150.jpeg 150w, https:\/\/iblow.eu\/wp-content\/uploads\/2022\/09\/Mariana-Martins-Fernandes.jpeg 400w\" data-sizes=\"(max-width: 128px) 100vw, 128px\" \/><\/p>\n<p>Dr. Daniel Reis<\/p>\n<p>Dr.\u00aa Marta Albuquerque Coelho<\/p>\n<p>Dr\u00aa Mariana Martins Fernandes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabia que\u2026 Os novos Regimes Gerais de Prote\u00e7\u00e3o de Denunciantes de Infra\u00e7\u00f5es e da Preven\u00e7\u00e3o da Corrup\u00e7\u00e3o encontram-se em vigor desde junho de 2022 e concretizam a Estrat\u00e9gia Nacional Anticorrup\u00e7\u00e3o 2020-2024? Existem agora novos direitos para denunciantes, bem como novas obriga\u00e7\u00f5es para as empresas, de modo a melhor acompanhar de uma forma segura den\u00fancias de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5935,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_ice_seo_score":0,"_ice_review":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-5934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/posts\/5934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/comments?post=5934"}],"version-history":[{"count":0,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/posts\/5934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/media\/5935"}],"wp:attachment":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/media?parent=5934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/categories?post=5934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/tags?post=5934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}