{"id":5975,"date":"2023-04-24T15:20:42","date_gmt":"2023-04-24T14:20:42","guid":{"rendered":"https:\/\/iblow.eu\/denuncias-externas-e-como-lidar-com-elas-um-guia-para-as-equipas-de-gestao-responsaveis-pelas-denuncias\/"},"modified":"2025-08-19T08:38:45","modified_gmt":"2025-08-19T07:38:45","slug":"denuncias-externas-e-como-lidar-com-elas-um-guia-para-as-equipas-de-gestao-responsaveis-pelas-denuncias","status":"publish","type":"post","link":"https:\/\/iblow.eu\/pt\/denuncias-externas-e-como-lidar-com-elas-um-guia-para-as-equipas-de-gestao-responsaveis-pelas-denuncias\/","title":{"rendered":"Den\u00fancias externas e como lidar com elas : um guia para as equipas de gest\u00e3o respons\u00e1veis pelas den\u00fancias"},"content":{"rendered":"<p><a href=\"https:\/\/iblow.eu\/pt\/denuncias-internas-e-como-lidar-com-elas\/\" target=\"_blank\" rel=\"noopener\">No artigo anterior<\/a>\u00a0falamos sobre a obriga\u00e7\u00e3o das entidades que ao abrigo da Lei n.\u00ba 93\/2021, de 20 de dezembro, est\u00e3o obrigadas a ado\u00e7\u00e3o de canais de den\u00fancias e institui\u00e7\u00e3o das regras a que deve obedecer a den\u00fancia interna.<\/p>\n<p>Como mencionado no referido artigo,\u00a0<strong>as infra\u00e7\u00f5es podem ser denunciadas por meio de canais de den\u00fancia internos ou externos ou divulgadas publicamente<\/strong>, estando previstas regras de utiliza\u00e7\u00e3o e de preced\u00eancia entre os diferentes meios.<\/p>\n<p>A dete\u00e7\u00e3o e a preven\u00e7\u00e3o eficazes de viola\u00e7\u00f5es do direito da Uni\u00e3o requerem a garantia de que os potenciais denunciantes possam comunicar, facilmente e com total confidencialidade, as informa\u00e7\u00f5es de que disp\u00f5em \u00e0s autoridades competentes para investigar e solucionar o problema, sempre que poss\u00edvel.<\/p>\n<h3>Preced\u00eancia entre os meios de den\u00fancia e divulga\u00e7\u00e3o p\u00fablica<\/h3>\n<p><strong>Em regra, o denunciante dever\u00e1 recorrer aos canais de den\u00fancia interna.\u00a0<\/strong>No entanto h\u00e1\u00a0<strong>casos em que os canais internos poder\u00e3o n\u00e3o existir ou ter sido utilizados, mas n\u00e3o funcionar corretamente<\/strong>, por exemplo, por a den\u00fancia n\u00e3o ter sido tratada com dilig\u00eancia ou num prazo razo\u00e1vel ou n\u00e3o terem sido tomadas as medidas adequadas para resolver a viola\u00e7\u00e3o, apesar dos resultados do respetivo inqu\u00e9rito interno confirmarem a exist\u00eancia de uma viola\u00e7\u00e3o.<\/p>\n<p>Noutros casos,\u00a0<strong>n\u00e3o \u00e9 razo\u00e1vel esperar que os canais internos funcionem corretamente<\/strong>. Tal acontece, particularmente, caso os denunciantes tenham raz\u00f5es v\u00e1lidas para crer que sofrer\u00e3o atos de retalia\u00e7\u00e3o devido \u00e0 den\u00fancia, nomeadamente em resultado da viola\u00e7\u00e3o da confidencialidade, ou que as autoridades competentes estar\u00e3o em melhor posi\u00e7\u00e3o para tomar medidas efetivas para resolver a viola\u00e7\u00e3o.<\/p>\n<p>As\u00a0<strong>autoridades competentes estar\u00e3o em melhor posi\u00e7\u00e3o<\/strong>, por exemplo, caso a pessoa sobre a qual recai a responsabilidade \u00faltima no contexto profissional esteja envolvida na viola\u00e7\u00e3o, ou exista um risco de a viola\u00e7\u00e3o ou as provas com ela relacionadas serem ocultadas ou destru\u00eddas, ou, em termos mais gerais, a efic\u00e1cia das medidas de investiga\u00e7\u00e3o das autoridades competentes poder ser comprometida, como no caso de den\u00fancias sobre carteliza\u00e7\u00e3o e outras viola\u00e7\u00f5es das regras de concorr\u00eancia, ou de a viola\u00e7\u00e3o exigir medidas urgentes, por exemplo, para proteger a sa\u00fade e a seguran\u00e7a das pessoas e proteger o ambiente.<\/p>\n<p>A\u00a0<strong>falta de confian\u00e7a na efetividade da den\u00fancia constitui um dos principais fatores desencorajantes dos potenciais denunciantes<\/strong>. Assim, \u00e9 necess\u00e1rio impor \u00e0s autoridades competentes uma obriga\u00e7\u00e3o clara de criarem os canais adequados para den\u00fancias externas, de darem um seguimento diligente \u00e0s den\u00fancias recebidas e, num prazo razo\u00e1vel, darem aos denunciantes retorno de informa\u00e7\u00e3o.<\/p>\n<p>O denunciante\u00a0<strong>s\u00f3 pode recorrer a canais de den\u00fancias externas<\/strong>\u00a0quando:<\/p>\n<p>\u2013 N\u00e3o exista canal de den\u00fancia interna;<\/p>\n<p>\u2013 O canal de den\u00fancia interna admita apenas a apresenta\u00e7\u00e3o de den\u00fancias por trabalhadores, n\u00e3o o sendo o denunciante;<\/p>\n<p>\u2013 Tenha motivos razo\u00e1veis para crer que a infra\u00e7\u00e3o n\u00e3o pode ser eficazmente conhecida ou resolvida a n\u00edvel interno ou que existe risco de retalia\u00e7\u00e3o;<\/p>\n<p>\u2013 Tenha inicialmente apresentado uma den\u00fancia interna sem que lhe tenham sido comunicadas as medidas previstas ou adotadas na sequ\u00eancia da den\u00fancia nos prazos previstos; ou<\/p>\n<p>\u2013 A infra\u00e7\u00e3o constitua crime ou contraordena\u00e7\u00e3o pun\u00edvel com coima superior a 50 000 (euro).<\/p>\n<h3>Capacidades das autoridades competentes<\/h3>\n<p>Enquanto recetoras das den\u00fancias, as autoridades designadas como competentes dever\u00e3o dispor das capacidades e dos poderes necess\u00e1rios para garantir o seguimento adequado, nomeadamente a aprecia\u00e7\u00e3o da exatid\u00e3o das alega\u00e7\u00f5es constantes da den\u00fancia e a resolu\u00e7\u00e3o das viola\u00e7\u00f5es denunciadas atrav\u00e9s da abertura de um inqu\u00e9rito interno, de uma investiga\u00e7\u00e3o, de a\u00e7\u00e3o penal, de uma medida de recupera\u00e7\u00e3o de fundos ou de outras medidas corretivas adequadas, nos termos do seu mandato.<\/p>\n<p>Em alternativa, essas autoridades dever\u00e3o dispor dos poderes necess\u00e1rios para remeter a den\u00fancia para outra autoridade que dever\u00e1 investigar a viola\u00e7\u00e3o denunciada, ao mesmo tempo que asseguram que \u00e9 dado o seguimento adequado por essa autoridade.<\/p>\n<h3>Autoridades competentes<\/h3>\n<p>As den\u00fancias externas s\u00e3o apresentadas \u00e0s autoridades que, de acordo com as suas atribui\u00e7\u00f5es e compet\u00eancias, devam ou possam conhecer da mat\u00e9ria em causa na den\u00fancia, incluindo:<\/p>\n<p>a) O Minist\u00e9rio P\u00fablico;<\/p>\n<p>b) Os \u00f3rg\u00e3os de pol\u00edcia criminal;<\/p>\n<p>c) O Banco de Portugal;<\/p>\n<p>d) As autoridades administrativas independentes;<\/p>\n<p>e) Os institutos p\u00fablicos;<\/p>\n<p>f) As inspe\u00e7\u00f5es-gerais e entidades equiparadas e outros servi\u00e7os centrais da administra\u00e7\u00e3o direta do Estado dotados de autonomia administrativa;<\/p>\n<p>g) As autarquias locais; e<\/p>\n<p>h) As associa\u00e7\u00f5es p\u00fablicas.<\/p>\n<p><strong>Quando seja apresentada a autoridade incompetente,<\/strong>\u00a0a den\u00fancia \u00e9 remetida oficiosamente \u00e0 autoridade competente, disso se notificando o denunciante, sendo que, neste caso, considera-se como data da rece\u00e7\u00e3o da den\u00fancia a data em que a autoridade competente a recebeu.<\/p>\n<p><strong>Nos casos em que n\u00e3o exista autoridade competente\u00a0<\/strong>para conhecer da den\u00fancia ou nos casos em que a den\u00fancia vise uma autoridade competente, deve a mesma ser dirigida ao Mecanismo Nacional Anticorrup\u00e7\u00e3o e, sendo esta a autoridade visada, ao Minist\u00e9rio P\u00fablico, que procede ao seu seguimento, designadamente atrav\u00e9s da abertura de inqu\u00e9rito sempre que os factos descritos na den\u00fancia constituam crime.<\/p>\n<p><strong>Se a infra\u00e7\u00e3o respeitar a crime ou a contraordena\u00e7\u00e3o<\/strong>, as den\u00fancias externas podem sempre ser apresentadas atrav\u00e9s dos canais de den\u00fancias externas do Minist\u00e9rio P\u00fablico ou dos \u00f3rg\u00e3os de pol\u00edcia criminal, quanto ao crime, e das autoridades administrativas competentes ou das autoridades policiais e fiscalizadoras, quanto \u00e0 contraordena\u00e7\u00e3o.<\/p>\n<h3>Seguimento da den\u00fancia externa<\/h3>\n<p>As autoridades competentes notificam o denunciante da rece\u00e7\u00e3o da den\u00fancia no\u00a0<strong>prazo de sete dias.<\/strong><\/p>\n<p>No seguimento da den\u00fancia, as autoridades competentes praticam os atos adequados \u00e0 verifica\u00e7\u00e3o das alega\u00e7\u00f5es a\u00ed contidas e, se for caso disso, \u00e0 cessa\u00e7\u00e3o da infra\u00e7\u00e3o denunciada, inclusive atrav\u00e9s da abertura de inqu\u00e9rito ou de processo ou da comunica\u00e7\u00e3o a autoridade competente.<\/p>\n<p>As autoridades competentes comunicam ao denunciante as medidas previstas ou adotadas para dar seguimento \u00e0 den\u00fancia e a respetiva fundamenta\u00e7\u00e3o no\u00a0<strong>prazo m\u00e1ximo de tr\u00eas meses<\/strong>\u00a0a contar da data da rece\u00e7\u00e3o da den\u00fancia, ou de seis meses quando a complexidade da den\u00fancia o justifique.<\/p>\n<p>O denunciante pode requerer, a qualquer momento, que as autoridades competentes lhe comuniquem o resultado da an\u00e1lise efetuada \u00e0 den\u00fancia no\u00a0<strong>prazo de 15 dias<\/strong>\u00a0ap\u00f3s a respetiva conclus\u00e3o.<\/p>\n<h3>Arquivamento das den\u00fancias<\/h3>\n<p>Para assegurar a efic\u00e1cia dos procedimentos para dar seguimento \u00e0s den\u00fancias e resolver as viola\u00e7\u00f5es das regras da Uni\u00e3o em causa, os Estados-Membros podem tomar medidas para aliviar os encargos para as autoridades competentes resultantes de den\u00fancias de viola\u00e7\u00f5es menores.<\/p>\n<p>Tais medidas consistem em permitir \u00e0s autoridades competentes, ap\u00f3s devida avalia\u00e7\u00e3o da mat\u00e9ria, decidirem que uma viola\u00e7\u00e3o denunciada tem manifestamente car\u00e1ter menor, n\u00e3o exigindo por isso outro seguimento, que n\u00e3o seja o arquivamento.<\/p>\n<h3>Obriga\u00e7\u00e3o de informa\u00e7\u00e3o<\/h3>\n<p>As pessoas que pretendem fazer den\u00fancias dever\u00e3o poder tomar uma decis\u00e3o esclarecida sobre se, como e quando o devem fazer. Por conseguinte, as autoridades competentes dever\u00e3o prestar informa\u00e7\u00f5es claras e facilmente acess\u00edveis sobre os canais dispon\u00edveis para den\u00fancias \u00e0s autoridades competentes, os procedimentos aplic\u00e1veis e o pessoal que \u00e9 respons\u00e1vel por tratar das den\u00fancias no contexto dessas autoridades. Todas as informa\u00e7\u00f5es relativas \u00e0 den\u00fancia de irregularidades dever\u00e3o ser transparentes, facilmente compreens\u00edveis e fi\u00e1veis, a fim de promover a den\u00fancia e n\u00e3o dissuadi-la.<\/p>\n<p>As autoridades competentes\u00a0<strong>publicam nos respetivos s\u00edtios na Internet<\/strong>, em sec\u00e7\u00e3o separada, facilmente identific\u00e1vel e acess\u00edvel, pelo menos as seguintes informa\u00e7\u00f5es:<\/p>\n<p>a) Condi\u00e7\u00f5es para beneficiar de prote\u00e7\u00e3o ao abrigo da lei ou ao abrigo dos regimes de prote\u00e7\u00e3o de denunciantes;<\/p>\n<p>b) Dados de contacto dos canais de den\u00fancias externas;<\/p>\n<p>c) Procedimentos aplic\u00e1veis \u00e0 den\u00fancia de infra\u00e7\u00f5es, nomeadamente a forma pela qual a autoridade competente pode solicitar ao denunciante que clarifique a den\u00fancia apresentada ou que preste informa\u00e7\u00f5es adicionais, inclusivamente em situa\u00e7\u00f5es de anonimato, e o prazo que a autoridade tem para prestar ao denunciante informa\u00e7\u00f5es fundamentadas sobre as medidas previstas ou tomadas para dar seguimento \u00e0 den\u00fancia;<\/p>\n<p>d) Regime de confidencialidade aplic\u00e1vel \u00e0s den\u00fancias;<\/p>\n<p>e) Tipo de medidas que podem ser tomadas para dar seguimento \u00e0s den\u00fancias;<\/p>\n<p>f) Vias de recurso e procedimentos de prote\u00e7\u00e3o contra atos de retalia\u00e7\u00e3o;<\/p>\n<p>g) Disponibilidade de aconselhamento confidencial para as pessoas que ponderam apresentar uma den\u00fancia; e<\/p>\n<p>h) Condi\u00e7\u00f5es em que o denunciante n\u00e3o incorre em responsabilidade por viola\u00e7\u00e3o de deveres de confidencialidade ou outros.<\/p>\n<h3>Cria\u00e7\u00e3o dos canais de den\u00fancia<\/h3>\n<p>A fim de permitir uma comunica\u00e7\u00e3o eficaz com o pessoal respons\u00e1vel por tratar das den\u00fancias, as autoridades competentes dever\u00e3o criar canais que sejam f\u00e1ceis de utilizar, seguros, garantam a confidencialidade para receber e tratar as informa\u00e7\u00f5es prestadas pelo denunciante sobre viola\u00e7\u00f5es e permitam o armazenamento duradouro de informa\u00e7\u00f5es para permitir investiga\u00e7\u00f5es mais aprofundadas.<\/p>\n<h3>Confidencialidade<\/h3>\n<p>A identidade do denunciante, bem como as informa\u00e7\u00f5es que, direta ou indiretamente, permitam deduzir\u00a0<strong>a sua identidade, t\u00eam natureza confidencial<\/strong>\u00a0e s\u00e3o de acesso restrito \u00e0s pessoas respons\u00e1veis por receber ou dar seguimento a den\u00fancias.<\/p>\n<p>A obriga\u00e7\u00e3o de confidencialidade referida estende-se a quem tiver recebido informa\u00e7\u00f5es sobre den\u00fancias, ainda que n\u00e3o respons\u00e1vel ou incompetente para a sua rece\u00e7\u00e3o e tratamento.<\/p>\n<p>A identidade do denunciante s\u00f3 \u00e9 divulgada em decorr\u00eancia de obriga\u00e7\u00e3o legal ou de decis\u00e3o judicial.<\/p>\n<h3>Respons\u00e1veis pelo tratamento de den\u00fancias externas<\/h3>\n<p>O pessoal das autoridades competentes que \u00e9 respons\u00e1vel pelo tratamento das den\u00fancias, dever\u00e1 ter\u00a0<strong>forma\u00e7\u00e3o profissional<\/strong>, nomeadamente sobre as normas aplic\u00e1veis em mat\u00e9ria de prote\u00e7\u00e3o de dados, para tratar das den\u00fancias e assegurar a comunica\u00e7\u00e3o com os respetivos denunciantes, bem como para dar o seguimento adequado \u00e0 den\u00fancia.<\/p>\n<h3>Tratamento de dados pessoais<\/h3>\n<p>O tratamento de dados pessoais ao abrigo da presente lei, incluindo o interc\u00e2mbio ou a transmiss\u00e3o de dados pessoais pelas autoridades competentes, observa o disposto no Regulamento Geral sobre a Prote\u00e7\u00e3o de Dados<a href=\"https:\/\/iblow.eu\/pt\/denuncias-externas-e-como-lidar-com-elas\/#_ftn1\" name=\"_ftnref1\">[1]<\/a>.<\/p>\n<p>\u00c9 necess\u00e1rio que o pessoal da autoridade competente, que \u00e9 respons\u00e1vel pelo tratamento de den\u00fancias, e o pessoal da autoridade competente, que tem direito a aceder \u00e0s informa\u00e7\u00f5es prestadas pelo denunciante, respeitem o dever de segredo profissional e de confidencialidade na transmiss\u00e3o dos dados no interior e para o exterior da autoridade competente.<\/p>\n<h3>Conserva\u00e7\u00e3o de den\u00fancias<\/h3>\n<p>As entidades obrigadas e as autoridades competentes respons\u00e1veis por receber e tratar den\u00fancias ao abrigo da presente lei devem manter um registo das den\u00fancias recebidas e conserv\u00e1-las, pelo menos, durante o per\u00edodo de\u00a0<strong>cinco anos<\/strong>\u00a0e, independentemente desse prazo, durante a pend\u00eancia de processos judiciais ou administrativos referentes \u00e0 den\u00fancia.<\/p>\n<p>Caso a den\u00fancia seja apresentada em reuni\u00e3o presencial, as entidades obrigadas e as autoridades competentes asseguram, obtido o consentimento do denunciante, o registo da reuni\u00e3o mediante:<\/p>\n<p>\u2013 Grava\u00e7\u00e3o da comunica\u00e7\u00e3o em suporte duradouro e recuper\u00e1vel; ou<\/p>\n<p>\u2013 Ata fidedigna.<\/p>\n<p>_______________________________<\/p>\n<p>[1] Aprovado pelo Regulamento (UE) 2016\/679 do Parlamento Europeu e do Conselho, de 27 de abril de 2016, na Lei n.\u00ba 58\/2019, de 8 de agosto, que assegura a execu\u00e7\u00e3o, na ordem jur\u00eddica nacional, do Regulamento (UE) 2016\/679, e na Lei n.\u00ba 59\/2019, de 8 de agosto, que aprova as regras relativas ao tratamento de dados pessoais para efeitos de preven\u00e7\u00e3o, dete\u00e7\u00e3o, investiga\u00e7\u00e3o ou repress\u00e3o de infra\u00e7\u00f5es penais ou de execu\u00e7\u00e3o de san\u00e7\u00f5es penais.<\/p>\n<p>Maria Cristina Freitas, Advogada<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No artigo anterior\u00a0falamos sobre a obriga\u00e7\u00e3o das entidades que ao abrigo da Lei n.\u00ba 93\/2021, de 20 de dezembro, est\u00e3o obrigadas a ado\u00e7\u00e3o de canais de den\u00fancias e institui\u00e7\u00e3o das regras a que deve obedecer a den\u00fancia interna. Como mencionado no referido artigo,\u00a0as infra\u00e7\u00f5es podem ser denunciadas por meio de canais de den\u00fancia internos ou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5977,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_ice_seo_score":0,"_ice_review":"","footnotes":""},"categories":[32],"tags":[],"class_list":["post-5975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/posts\/5975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/comments?post=5975"}],"version-history":[{"count":0,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/posts\/5975\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/media\/5977"}],"wp:attachment":[{"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/media?parent=5975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/categories?post=5975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iblow.eu\/pt\/wp-json\/wp\/v2\/tags?post=5975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}